{"id":49297,"date":"2023-02-13T09:59:04","date_gmt":"2023-02-13T08:59:04","guid":{"rendered":"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/extrait-bio-2023.webp"},"modified":"2023-05-25T15:05:56","modified_gmt":"2023-05-25T13:05:56","slug":"extrait-bio-2023-2-2","status":"inherit","type":"attachment","link":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/","title":{"rendered":"estratto organico 2023"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-49297","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Wesley LIBLIN\"\/>\n\t<meta name=\"google-site-verification\" content=\"7oFrR9Lqm_aVqX0_DvgyPqTZtSnzpIsU709dUSOcx24\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<link rel=\"dns-prefetch\" href=\"https:\/\/www.google-analytics.com\">\n<link rel=\"dns-prefetch\" href=\"https:\/\/fonts.gstatic.com\">\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le monde de la vanille - Import Export de Vanille du Monde - Gros \u2013 Demi-gros \u2013 D\u00e9tail\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"estratto organico 2023 - Le monde de la vanille\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/le-monde-de-la-vanille-logo-1626945292.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/le-monde-de-la-vanille-logo-1626945292.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-13T08:59:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-25T13:05:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mondevanille\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"estratto organico 2023 - Le monde de la vanille\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/le-monde-de-la-vanille-logo-1626945292.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#listItem\",\"name\":\"estratto organico 2023\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#listItem\",\"position\":2,\"name\":\"estratto organico 2023\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#itempage\",\"url\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/\",\"name\":\"estratto organico 2023 - Le monde de la vanille\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/author\\\/liblinmondevanille-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/author\\\/liblinmondevanille-com\\\/#author\"},\"datePublished\":\"2023-02-13T09:59:04+01:00\",\"dateModified\":\"2023-05-25T15:05:56+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/#organization\",\"name\":\"Le Monde de la Vanille\",\"description\":\"Import Export de Vanille du Monde - Gros \\u2013 Demi-gros \\u2013 D\\u00e9tail\",\"url\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/\",\"email\":\"contact@mondevanille.com\",\"telephone\":\"+33235245220\",\"foundingDate\":\"1995-10-03\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/mondevanille.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-logocarre.png\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#organizationLogo\",\"width\":512,\"height\":512,\"caption\":\"Logo Le Monde de la Vanille\"},\"image\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mondevanille\",\"https:\\\/\\\/www.instagram.com\\\/mondevanille\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/le-monde-de-la-vanille\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/author\\\/liblinmondevanille-com\\\/#author\",\"url\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/author\\\/liblinmondevanille-com\\\/\",\"name\":\"Wesley LIBLIN\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#webpage\",\"url\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/\",\"name\":\"estratto organico 2023 - Le monde de la vanille\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/extrait-bio-2023-2-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/author\\\/liblinmondevanille-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/author\\\/liblinmondevanille-com\\\/#author\"},\"datePublished\":\"2023-02-13T09:59:04+01:00\",\"dateModified\":\"2023-05-25T15:05:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/\",\"name\":\"Le Monde de la Vanille\",\"alternateName\":\"Gousse de Vanille pour professionnel et particulier\",\"description\":\"Import Export de Vanille du Monde - Gros \\u2013 Demi-gros \\u2013 D\\u00e9tail\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/mondevanille.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-KZRMNVV\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>estratto organico 2023 - Le monde de la vanille<\/title>\n\n","aioseo_head_json":{"title":"estratto organico 2023 - Le monde de la vanille","description":"","canonical_url":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"7oFrR9Lqm_aVqX0_DvgyPqTZtSnzpIsU709dUSOcx24","miscellaneous":"&lt;link rel=\"dns-prefetch\" href=\"https:\/\/www.google-analytics.com\"&gt;\n&lt;link rel=\"dns-prefetch\" href=\"https:\/\/fonts.gstatic.com\"&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mondevanille.com\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/mondevanille.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#listItem","name":"estratto organico 2023"}},{"@type":"ListItem","@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#listItem","position":2,"name":"estratto organico 2023","previousItem":{"@type":"ListItem","@id":"https:\/\/mondevanille.com\/it\/#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#itempage","url":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/","name":"estratto organico 2023 - Le monde de la vanille","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/mondevanille.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#breadcrumblist"},"author":{"@id":"https:\/\/mondevanille.com\/it\/author\/liblinmondevanille-com\/#author"},"creator":{"@id":"https:\/\/mondevanille.com\/it\/author\/liblinmondevanille-com\/#author"},"datePublished":"2023-02-13T09:59:04+01:00","dateModified":"2023-05-25T15:05:56+02:00"},{"@type":"Organization","@id":"https:\/\/mondevanille.com\/it\/#organization","name":"Le Monde de la Vanille","description":"Import Export de Vanille du Monde - Gros \u2013 Demi-gros \u2013 D\u00e9tail","url":"https:\/\/mondevanille.com\/it\/","email":"contact@mondevanille.com","telephone":"+33235245220","foundingDate":"1995-10-03","logo":{"@type":"ImageObject","url":"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/cropped-logocarre.png","@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#organizationLogo","width":512,"height":512,"caption":"Logo Le Monde de la Vanille"},"image":{"@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/mondevanille","https:\/\/www.instagram.com\/mondevanille\/","https:\/\/www.linkedin.com\/company\/le-monde-de-la-vanille\/"]},{"@type":"Person","@id":"https:\/\/mondevanille.com\/it\/author\/liblinmondevanille-com\/#author","url":"https:\/\/mondevanille.com\/it\/author\/liblinmondevanille-com\/","name":"Wesley LIBLIN"},{"@type":"WebPage","@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#webpage","url":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/","name":"estratto organico 2023 - Le monde de la vanille","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/mondevanille.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/#breadcrumblist"},"author":{"@id":"https:\/\/mondevanille.com\/it\/author\/liblinmondevanille-com\/#author"},"creator":{"@id":"https:\/\/mondevanille.com\/it\/author\/liblinmondevanille-com\/#author"},"datePublished":"2023-02-13T09:59:04+01:00","dateModified":"2023-05-25T15:05:56+02:00"},{"@type":"WebSite","@id":"https:\/\/mondevanille.com\/it\/#website","url":"https:\/\/mondevanille.com\/it\/","name":"Le Monde de la Vanille","alternateName":"Gousse de Vanille pour professionnel et particulier","description":"Import Export de Vanille du Monde - Gros \u2013 Demi-gros \u2013 D\u00e9tail","inLanguage":"it-IT","publisher":{"@id":"https:\/\/mondevanille.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Le monde de la vanille - Import Export de Vanille du Monde - Gros \u2013 Demi-gros \u2013 D\u00e9tail","og:type":"article","og:title":"estratto organico 2023 - Le monde de la vanille","og:url":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/","og:image":"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/le-monde-de-la-vanille-logo-1626945292.png","og:image:secure_url":"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/le-monde-de-la-vanille-logo-1626945292.png","article:published_time":"2023-02-13T08:59:04+00:00","article:modified_time":"2023-05-25T13:05:56+00:00","article:publisher":"https:\/\/www.facebook.com\/mondevanille","twitter:card":"summary","twitter:title":"estratto organico 2023 - Le monde de la vanille","twitter:image":"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/le-monde-de-la-vanille-logo-1626945292.png"},"aioseo_meta_data":{"post_id":"49297","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2023-06-09 17:24:03","updated":"2025-06-05 12:36:47","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/mondevanille.com\/it\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\testratto organico 2023\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mondevanille.com\/it\/"},{"label":"estratto organico 2023","link":"https:\/\/mondevanille.com\/it\/extrait-bio-2023-2-2\/"}],"description":{"rendered":"<p class=\"attachment\"><a data-open=\"modal-6a989c4972089\"><img fetchpriority=\"high\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/extrait-bio-2023.webp\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" \/><\/a><div class=\"full reveal gb-gallery\" id=\"modal-6a989c4972089\" data-reveal>\n                    <img decoding=\"async\" src=\"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/extrait-bio-2023.webp\" \/>\n                      <button class=\"gb-gallery-btn close-button\" data-close type=\"button\">\n                      <\/button>\n                      <button class=\"gb-gallery-btn next\"><\/button>\n                      <button class=\"gb-gallery-btn prev\"><\/button>\n                    <\/div><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/webp","media_details":{"width":1200,"height":1600,"file":"2021\/02\/extrait-bio-2023.webp","filesize":52458,"sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/extrait-bio-2023.webp","filename":"extrait-bio-2023.webp","filesize":52458,"source_url_webp":"https:\/\/mondevanille.com\/wp-content\/uploads\/2021\/02\/extrait-bio-2023.webp","_links":{"self":[{"href":"https:\/\/mondevanille.com\/it\/wp-json\/wp\/v2\/media\/49297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mondevanille.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mondevanille.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mondevanille.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mondevanille.com\/it\/wp-json\/wp\/v2\/comments?post=49297"}]}}